{"id":13522,"date":"2021-10-12T17:59:37","date_gmt":"2021-10-12T22:59:37","guid":{"rendered":"https:\/\/wttedwwtp3.wpdns.site\/product\/pink-coral-cosmos-mix\/"},"modified":"2024-02-29T20:53:22","modified_gmt":"2024-03-01T01:53:22","slug":"pink-coral-cosmos-mix","status":"publish","type":"product","link":"https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/","title":{"rendered":"Pink Coral Cosmos Mix"},"content":{"rendered":"<p>Cosmos is an annual plant, native to Mexico. The color of the Coral mix varies from white to dark pink.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>10 x \/ pack<\/p>\n","protected":false},"featured_media":11202,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[288,277,301],"product_tag":[],"class_list":["post-13522","product","type-product","status-publish","has-post-thumbnail","product_cat-cosmos-en","product_cat-flowers","product_cat-mix-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image","entry","content-bg","loop-entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pink Coral Cosmos Mix - Semence Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pink Coral Cosmos Mix - Semence Canada\" \/>\n<meta property=\"og:description\" content=\"10 x \/ pack\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/\" \/>\n<meta property=\"og:site_name\" content=\"Semence Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-01T01:53:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semencecanada.com\/wp-content\/uploads\/2021\/10\/cosmos-mix-corail-semence-canada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/pink-coral-cosmos-mix\\\/\",\"url\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/pink-coral-cosmos-mix\\\/\",\"name\":\"Pink Coral Cosmos Mix - Semence Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semencecanada.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/pink-coral-cosmos-mix\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/pink-coral-cosmos-mix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semencecanada.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cosmos-mix-corail-semence-canada.jpg\",\"datePublished\":\"2021-10-12T22:59:37+00:00\",\"dateModified\":\"2024-03-01T01:53:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/pink-coral-cosmos-mix\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/pink-coral-cosmos-mix\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/pink-coral-cosmos-mix\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semencecanada.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cosmos-mix-corail-semence-canada.jpg\",\"contentUrl\":\"https:\\\/\\\/semencecanada.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cosmos-mix-corail-semence-canada.jpg\",\"width\":700,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/pink-coral-cosmos-mix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pink Coral Cosmos Mix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semencecanada.com\\\/#website\",\"url\":\"https:\\\/\\\/semencecanada.com\\\/\",\"name\":\"Semence Canada\",\"description\":\"La Seed Bank #1 au Canada\",\"publisher\":{\"@id\":\"https:\\\/\\\/semencecanada.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semencecanada.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semencecanada.com\\\/#organization\",\"name\":\"Semence Canada\",\"url\":\"https:\\\/\\\/semencecanada.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semencecanada.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semencecanada.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nobackground-1.png\",\"contentUrl\":\"https:\\\/\\\/semencecanada.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nobackground-1.png\",\"width\":394,\"height\":121,\"caption\":\"Semence Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/semencecanada.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pink Coral Cosmos Mix - Semence Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/","og_locale":"en_US","og_type":"article","og_title":"Pink Coral Cosmos Mix - Semence Canada","og_description":"10 x \/ pack","og_url":"https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/","og_site_name":"Semence Canada","article_modified_time":"2024-03-01T01:53:22+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/semencecanada.com\/wp-content\/uploads\/2021\/10\/cosmos-mix-corail-semence-canada.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/","url":"https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/","name":"Pink Coral Cosmos Mix - Semence Canada","isPartOf":{"@id":"https:\/\/semencecanada.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/#primaryimage"},"image":{"@id":"https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/#primaryimage"},"thumbnailUrl":"https:\/\/semencecanada.com\/wp-content\/uploads\/2021\/10\/cosmos-mix-corail-semence-canada.jpg","datePublished":"2021-10-12T22:59:37+00:00","dateModified":"2024-03-01T01:53:22+00:00","breadcrumb":{"@id":"https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/#primaryimage","url":"https:\/\/semencecanada.com\/wp-content\/uploads\/2021\/10\/cosmos-mix-corail-semence-canada.jpg","contentUrl":"https:\/\/semencecanada.com\/wp-content\/uploads\/2021\/10\/cosmos-mix-corail-semence-canada.jpg","width":700,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/semencecanada.com\/en\/product\/pink-coral-cosmos-mix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/semencecanada.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/semencecanada.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Pink Coral Cosmos Mix"}]},{"@type":"WebSite","@id":"https:\/\/semencecanada.com\/#website","url":"https:\/\/semencecanada.com\/","name":"Semence Canada","description":"La Seed Bank #1 au Canada","publisher":{"@id":"https:\/\/semencecanada.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semencecanada.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/semencecanada.com\/#organization","name":"Semence Canada","url":"https:\/\/semencecanada.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semencecanada.com\/#\/schema\/logo\/image\/","url":"https:\/\/semencecanada.com\/wp-content\/uploads\/2022\/01\/logo-nobackground-1.png","contentUrl":"https:\/\/semencecanada.com\/wp-content\/uploads\/2022\/01\/logo-nobackground-1.png","width":394,"height":121,"caption":"Semence Canada"},"image":{"@id":"https:\/\/semencecanada.com\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"product_cat":[{"value":288,"label":"Cosmos"},{"value":277,"label":"Flowers"},{"value":301,"label":"Mix"}]},"featured_image_src_large":["https:\/\/semencecanada.com\/wp-content\/uploads\/2021\/10\/cosmos-mix-corail-semence-canada.jpg",700,700,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/product\/13522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/media\/11202"}],"wp:attachment":[{"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/media?parent=13522"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/product_brand?post=13522"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/product_cat?post=13522"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/product_tag?post=13522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}