{"id":13516,"date":"2021-10-12T16:04:53","date_gmt":"2021-10-12T21:04:53","guid":{"rendered":"https:\/\/wttedwwtp3.wpdns.site\/product\/el-dorado-zinnia\/"},"modified":"2025-01-05T10:22:45","modified_gmt":"2025-01-05T15:22:45","slug":"el-dorado-zinnia","status":"publish","type":"product","link":"https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/","title":{"rendered":"El Dorado Zinnia"},"content":{"rendered":"<p>As dependable as it is beautiful, this medium to large double flowered zinnia does not disappoint. The striking salmon orange color is amazing in arrangements. The rods are super stiff and perfect for cutting.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>15 x \/ pack<\/p>\n","protected":false},"featured_media":12439,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[277,314],"product_tag":[],"class_list":["post-13516","product","type-product","status-publish","has-post-thumbnail","product_cat-flowers","product_cat-zinnia-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-before_image","entry","content-bg","loop-entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Dorado Zinnia - Semence Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Dorado Zinnia - Semence Canada\" \/>\n<meta property=\"og:description\" content=\"15 x \/ pack\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/\" \/>\n<meta property=\"og:site_name\" content=\"Semence Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-05T15:22:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semencecanada.com\/wp-content\/uploads\/2021\/10\/zinnia-eldorado-semence-canada-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/el-dorado-zinnia\\\/\",\"url\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/el-dorado-zinnia\\\/\",\"name\":\"El Dorado Zinnia - Semence Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semencecanada.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/el-dorado-zinnia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/el-dorado-zinnia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semencecanada.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/zinnia-eldorado-semence-canada-1.jpg\",\"datePublished\":\"2021-10-12T21:04:53+00:00\",\"dateModified\":\"2025-01-05T15:22:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/el-dorado-zinnia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/el-dorado-zinnia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/el-dorado-zinnia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semencecanada.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/zinnia-eldorado-semence-canada-1.jpg\",\"contentUrl\":\"https:\\\/\\\/semencecanada.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/zinnia-eldorado-semence-canada-1.jpg\",\"width\":1920,\"height\":1260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/product\\\/el-dorado-zinnia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/semencecanada.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El Dorado Zinnia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semencecanada.com\\\/#website\",\"url\":\"https:\\\/\\\/semencecanada.com\\\/\",\"name\":\"Semence Canada\",\"description\":\"La Seed Bank #1 au Canada\",\"publisher\":{\"@id\":\"https:\\\/\\\/semencecanada.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semencecanada.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semencecanada.com\\\/#organization\",\"name\":\"Semence Canada\",\"url\":\"https:\\\/\\\/semencecanada.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semencecanada.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semencecanada.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nobackground-1.png\",\"contentUrl\":\"https:\\\/\\\/semencecanada.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-nobackground-1.png\",\"width\":394,\"height\":121,\"caption\":\"Semence Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/semencecanada.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Dorado Zinnia - Semence Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/","og_locale":"en_US","og_type":"article","og_title":"El Dorado Zinnia - Semence Canada","og_description":"15 x \/ pack","og_url":"https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/","og_site_name":"Semence Canada","article_modified_time":"2025-01-05T15:22:45+00:00","og_image":[{"width":1920,"height":1260,"url":"https:\/\/semencecanada.com\/wp-content\/uploads\/2021\/10\/zinnia-eldorado-semence-canada-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/","url":"https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/","name":"El Dorado Zinnia - Semence Canada","isPartOf":{"@id":"https:\/\/semencecanada.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/#primaryimage"},"image":{"@id":"https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/#primaryimage"},"thumbnailUrl":"https:\/\/semencecanada.com\/wp-content\/uploads\/2021\/10\/zinnia-eldorado-semence-canada-1.jpg","datePublished":"2021-10-12T21:04:53+00:00","dateModified":"2025-01-05T15:22:45+00:00","breadcrumb":{"@id":"https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/#primaryimage","url":"https:\/\/semencecanada.com\/wp-content\/uploads\/2021\/10\/zinnia-eldorado-semence-canada-1.jpg","contentUrl":"https:\/\/semencecanada.com\/wp-content\/uploads\/2021\/10\/zinnia-eldorado-semence-canada-1.jpg","width":1920,"height":1260},{"@type":"BreadcrumbList","@id":"https:\/\/semencecanada.com\/en\/product\/el-dorado-zinnia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/semencecanada.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/semencecanada.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"El Dorado Zinnia"}]},{"@type":"WebSite","@id":"https:\/\/semencecanada.com\/#website","url":"https:\/\/semencecanada.com\/","name":"Semence Canada","description":"La Seed Bank #1 au Canada","publisher":{"@id":"https:\/\/semencecanada.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semencecanada.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/semencecanada.com\/#organization","name":"Semence Canada","url":"https:\/\/semencecanada.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semencecanada.com\/#\/schema\/logo\/image\/","url":"https:\/\/semencecanada.com\/wp-content\/uploads\/2022\/01\/logo-nobackground-1.png","contentUrl":"https:\/\/semencecanada.com\/wp-content\/uploads\/2022\/01\/logo-nobackground-1.png","width":394,"height":121,"caption":"Semence Canada"},"image":{"@id":"https:\/\/semencecanada.com\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"product_cat":[{"value":277,"label":"Flowers"},{"value":314,"label":"Zinnia"}]},"featured_image_src_large":["https:\/\/semencecanada.com\/wp-content\/uploads\/2021\/10\/zinnia-eldorado-semence-canada-1.jpg",1024,672,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/product\/13516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/media\/12439"}],"wp:attachment":[{"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/media?parent=13516"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/product_brand?post=13516"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/product_cat?post=13516"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/semencecanada.com\/en\/wp-json\/wp\/v2\/product_tag?post=13516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}